{"id":176217,"date":"2022-09-05T05:31:06","date_gmt":"2022-09-05T05:31:06","guid":{"rendered":"https:\/\/dev.fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1.jpeg"},"modified":"2022-09-05T05:31:06","modified_gmt":"2022-09-05T05:31:06","slug":"tempimageufbdhm-800x1067-2","status":"inherit","type":"attachment","link":"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/","title":{"rendered":"tempImageuFBdHM-800&#215;1067"},"author":19,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-176217","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>tempImageuFBdHM-800x1067 - Fil De Fer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tempImageuFBdHM-800x1067 - Fil De Fer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fil De Fer\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/\",\"url\":\"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/\",\"name\":\"tempImageuFBdHM-800x1067 - Fil De Fer\",\"isPartOf\":{\"@id\":\"https:\/\/fildefercph.com\/#website\"},\"datePublished\":\"2022-09-05T05:31:06+00:00\",\"dateModified\":\"2022-09-05T05:31:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/fildefercph.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tempImageuFBdHM-800&#215;1067\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fildefercph.com\/#website\",\"url\":\"https:\/\/fildefercph.com\/\",\"name\":\"Fil De Fer\",\"description\":\"Unique antiques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fildefercph.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"tempImageuFBdHM-800x1067 - Fil De Fer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/","og_locale":"en_US","og_type":"article","og_title":"tempImageuFBdHM-800x1067 - Fil De Fer","og_url":"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/","og_site_name":"Fil De Fer","og_image":[{"width":800,"height":1067,"url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/","url":"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/","name":"tempImageuFBdHM-800x1067 - Fil De Fer","isPartOf":{"@id":"https:\/\/fildefercph.com\/#website"},"datePublished":"2022-09-05T05:31:06+00:00","dateModified":"2022-09-05T05:31:06+00:00","breadcrumb":{"@id":"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fildefercph.com\/en\/tempimageufbdhm-800x1067-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/fildefercph.com\/en\/"},{"@type":"ListItem","position":2,"name":"tempImageuFBdHM-800&#215;1067"}]},{"@type":"WebSite","@id":"https:\/\/fildefercph.com\/#website","url":"https:\/\/fildefercph.com\/","name":"Fil De Fer","description":"Unique antiques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fildefercph.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-225x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":1067,"file":"2022\/06\/tempImageuFBdHM-800x1067-1.jpeg","filesize":132659,"sizes":{"medium":{"file":"tempImageuFBdHM-800x1067-1-225x300.jpeg","width":225,"height":300,"filesize":16533,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-225x300.jpeg"},"thumbnail":{"file":"tempImageuFBdHM-800x1067-1-150x150.jpeg","width":150,"height":150,"filesize":6721,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-150x150.jpeg"},"grid-wide":{"file":"tempImageuFBdHM-800x1067-1-334x249.jpeg","width":334,"height":249,"filesize":17242,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-334x249.jpeg"},"grid-tall":{"file":"tempImageuFBdHM-800x1067-1-334x441.jpeg","width":334,"height":441,"filesize":30686,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-334x441.jpeg"},"square-large":{"file":"tempImageuFBdHM-800x1067-1-525x525.jpeg","width":525,"height":525,"filesize":48638,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-525x525.jpeg"},"rectangle-large":{"file":"tempImageuFBdHM-800x1067-1-1040x520.jpeg","width":1040,"height":520,"filesize":65376,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-1040x520.jpeg"},"blog-wide":{"file":"tempImageuFBdHM-800x1067-1-1050x350.jpeg","width":1050,"height":350,"filesize":44441,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-1050x350.jpeg"},"woocommerce_thumbnail":{"file":"tempImageuFBdHM-800x1067-1-300x300.jpeg","width":300,"height":300,"filesize":19975,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-300x300.jpeg"},"woocommerce_gallery_thumbnail":{"file":"tempImageuFBdHM-800x1067-1-100x100.jpeg","width":100,"height":100,"filesize":3828,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1-100x100.jpeg"},"full":{"file":"tempImageuFBdHM-800x1067-1.jpeg","width":800,"height":1067,"mime_type":"image\/jpeg","source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/fildefercph.com\/wp-content\/uploads\/2022\/06\/tempImageuFBdHM-800x1067-1.jpeg","_links":{"self":[{"href":"https:\/\/fildefercph.com\/en\/wp-json\/wp\/v2\/media\/176217"}],"collection":[{"href":"https:\/\/fildefercph.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/fildefercph.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/fildefercph.com\/en\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/fildefercph.com\/en\/wp-json\/wp\/v2\/comments?post=176217"}]}}